{"id":6,"date":"2023-01-30T11:29:40","date_gmt":"2023-01-30T10:29:40","guid":{"rendered":"http:\/\/staging.crmcosmo.com\/biofonic?page_id=6"},"modified":"2026-08-24T10:24:13","modified_gmt":"2026-08-24T08:24:13","slug":"homepage","status":"publish","type":"page","link":"https:\/\/staging.crmcosmo.com\/audire\/","title":{"rendered":"Homepage"},"content":{"rendered":"\n<section class=\"audire-hero\" style=\"background-image: url('https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/05\/audire-roma-soluzioni-acustiche-su-misura.jpg');\">\n    <div class=\"audire-hero__overlay\"><\/div>\n    <div class=\"audire-hero__inner\">\n\n        <!-- Box Testi in Sovraimpressione (Glassmorphism) -->\n        <div class=\"audire-hero__card\">\n\n            <!-- Tag Badge Clinico di Fiducia -->\n            <div class=\"audire-hero__badge\">\n                <span class=\"audire-hero__badge-icon\">\ud83c\udfc6<\/span>\n                <span class=\"audire-hero__badge-text\">La vicinanza costante \u00e8 il primo gesto di cura<\/span>\n                <span class=\"audire-hero__badge-separator\"><\/span>\n                <span class=\"audire-hero__badge-partner\">Partner Artemisia Lab<\/span>\n            <\/div>\n\n            <!-- Titolo Principale (Font Outfit) -->\n            <h1 class=\"audire-hero__title\">\n                Migliora il suono<br>\n                <span class=\"audire-hero__title-accent\">\n                    intorno a te.                <\/span>\n            <\/h1>\n\n            <!-- Descrizione Testo -->\n            <p class=\"audire-hero__description\">\n                Ipoacusia e ronzii non devono isolarti dagli affetti. Audire Roma offre soluzioni acustiche su misura e invisibili, supportate da medici esperti e dalla rete diagnostica d&#039;eccellenza Artemisia Lab.            <\/p>\n\n            <!-- Pulsanti Direct Action -->\n            <div class=\"audire-hero__actions\">\n                <a href=\"\/chi-siamo\" class=\"audire-hero__btn audire-hero__btn--secondary\">\n                    Conosci il Team                <\/a>\n                <a href=\"#test-udito\" class=\"audire-hero__btn audire-hero__btn--primary\">\n                    Fai il Test Udito Online                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\"\n                        stroke=\"currentColor\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\n                        class=\"audire-hero__btn-arrow\">\n                        <line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"><\/line>\n                        <polyline points=\"12 5 19 12 12 19\"><\/polyline>\n                    <\/svg>\n                <\/a>\n            <\/div>\n\n        <\/div>\n\n        <!-- Colonna Bullet Points Rassicuranti in Overlay -->\n        <div class=\"audire-hero__checks-wrapper\">\n                            <div class=\"audire-hero__check-card\">\n                    <span class=\"audire-hero__check-icon\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 24 24\" fill=\"none\"\n                            stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                            <polyline points=\"20 6 9 17 4 12\"><\/polyline>\n                        <\/svg>\n                    <\/span>\n                    <span class=\"audire-hero__check-text\">Prova gratuita 30 giorni a casa<\/span>\n                <\/div>\n                            <div class=\"audire-hero__check-card\">\n                    <span class=\"audire-hero__check-icon\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 24 24\" fill=\"none\"\n                            stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                            <polyline points=\"20 6 9 17 4 12\"><\/polyline>\n                        <\/svg>\n                    <\/span>\n                    <span class=\"audire-hero__check-text\">Convenzioni totali ASL \/ INAIL<\/span>\n                <\/div>\n                            <div class=\"audire-hero__check-card\">\n                    <span class=\"audire-hero__check-icon\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 24 24\" fill=\"none\"\n                            stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                            <polyline points=\"20 6 9 17 4 12\"><\/polyline>\n                        <\/svg>\n                    <\/span>\n                    <span class=\"audire-hero__check-text\">Moderne tecnologie ricaricabili<\/span>\n                <\/div>\n                            <div class=\"audire-hero__check-card\">\n                    <span class=\"audire-hero__check-icon\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 24 24\" fill=\"none\"\n                            stroke=\"currentColor\" stroke-width=\"3\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                            <polyline points=\"20 6 9 17 4 12\"><\/polyline>\n                        <\/svg>\n                    <\/span>\n                    <span class=\"audire-hero__check-text\">Screening gratuito dell&#039;udito<\/span>\n                <\/div>\n                    <\/div>\n\n    <\/div>\n<\/section>\n\n<section class=\"audire-pref\" id=\"sound-preference\">\n    <div class=\"audire-pref__inner\">\n        \n        <!-- Header del Blocco -->\n        <div class=\"audire-pref__header\">\n            <span class=\"audire-pref__badge\">ESCLUSIVA AUDIRE ROMA<\/span>\n            <h2 class=\"audire-pref__title\">Il nostro Plus: SOS Audire<\/h2>\n            <p class=\"audire-pref__subtitle\">Un servizio pensato per offrirti supporto per il tuo apparecchio acustico, di qualsiasi marca, anche se non sei gi\u00e0 cliente Audire. Un aiuto semplice e veloce, direttamente a casa tua.<\/p>\n        <\/div>\n\n        <!-- Griglia a 3 Colonne con lo stesso peso per tutti i punti -->\n        <div class=\"audire-pref__grid\">\n            \n            <!-- Punto 1 -->\n            <div class=\"audire-pref__card\">\n                <div class=\"audire-pref__card-num\">01<\/div>\n                <h3 class=\"audire-pref__card-title\">Hai bisogno di assistenza? Arriviamo noi da te<\/h3>\n                <p class=\"audire-pref__card-text\">Quando hai bisogno di controllare il tuo apparecchio acustico, non sempre \u00e8 facile spostarsi. Con SOS Audire puoi richiedere un intervento direttamente a casa tua, in modo semplice e veloce.<\/p>\n            <\/div>\n\n            <!-- Punto 2 -->\n            <div class=\"audire-pref__card\">\n                <div class=\"audire-pref__card-num\">02<\/div>\n                <h3 class=\"audire-pref__card-title\">Un pronto intervento, senza inutili attese<\/h3>\n                <p class=\"audire-pref__card-text\">SOS Audire \u00e8 pensato per offrirti un supporto rapido direttamente a domicilio, cos\u00ec puoi ricevere l&#039;assistenza di cui hai bisogno senza doverti recare presso il centro acustico.<\/p>\n            <\/div>\n\n            <!-- Punto 3 -->\n            <div class=\"audire-pref__card\">\n                <div class=\"audire-pref__card-num\">03<\/div>\n                <h3 class=\"audire-pref__card-title\">A soli 39 \u20ac a intervento<\/h3>\n                <p class=\"audire-pref__card-text\">Un servizio semplice e trasparente, con una tariffa fissa di soli 39 \u20ac per l&#039;intervento a domicilio. Per ricevere assistenza in modo comodo, rapido e senza sorprese.<\/p>\n            <\/div>\n\n        <\/div>\n\n        <!-- Banner di Chiusura -->\n                <div class=\"audire-pref__footer-box\">\n            <span class=\"audire-pref__footer-icon\">\u2728<\/span>\n            <p class=\"audire-pref__footer-text\">Per un suono estremamente naturale, confortevole e perfettamente in linea con le tue aspettative.<\/p>\n        <\/div>\n        \n    <\/div>\n<\/section>\n\n<section class=\"audire-products\">\n    <div class=\"audire-products__inner\">\n        <div class=\"audire-products__header\">\n            <div class=\"audire-products__header-texts\">\n                <span class=\"audire-products__badge\">Piattaforma Tecnologica<\/span>\n                <h2 class=\"audire-products__title\">Apparecchi acustici e ultima tecnologia<\/h2>\n            <\/div>\n\n            <!-- CONTROLLI TAB ATTIVI CON NAVIGAZIONE FRECCE -->\n            <div class=\"audire-products__nav-wrapper\">\n\n                <div class=\"audire-products__tabs\">\n                                            <button type=\"button\"\n                            class=\"audire-products__tab-btn \"\n                            data-target=\"p-signia-silk-chargego-ix-788\">\n                            Silk                        <\/button>\n                                            <button type=\"button\"\n                            class=\"audire-products__tab-btn is-active\"\n                            data-target=\"p-signia-pure-chargego-ix-793\">\n                            Pure                        <\/button>\n                                            <button type=\"button\"\n                            class=\"audire-products__tab-btn \"\n                            data-target=\"p-connettivita-intelligente-984\">\n                            Connettivit\u00e0                        <\/button>\n                                            <button type=\"button\"\n                            class=\"audire-products__tab-btn \"\n                            data-target=\"p-telemedicina-986\">\n                            Telemedicina                        <\/button>\n                                    <\/div>\n\n            <\/div>\n        <\/div>\n\n        <div class=\"audire-products__list\">\n                            <div class=\"audire-product-panel \"\n                    id=\"p-signia-silk-chargego-ix-788\">\n                    <div class=\"audire-product-item-grid\">\n\n                        <!-- Frecce di navigazione desktop fluttuanti ai lati della scheda -->\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--prev\"\n                            aria-label=\"Prodotto precedente\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"15 18 9 12 15 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--next\"\n                            aria-label=\"Prodotto successivo\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"9 18 15 12 9 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Sinistra: Info Prodotto -->\n                        <div class=\"audire-product-item-left\">\n                                                        <div class=\"audire-product-item__meta\">\n                                <span class=\"audire-product-item__tag\">Discrezione e Innovazione<\/span>\n                                <span class=\"audire-product-item__sep\">|<\/span>\n                                <span class=\"audire-product-item__tech\">Tecnologia\n                                    Premium<\/span>\n                            <\/div>\n                            \n                            <h3 class=\"audire-product-item__name\">Signia Silk Charge&amp;Go IX<\/h3>\n                            <p class=\"audire-product-item__description\">Piccolo nelle dimensioni, grande nelle prestazioni. Signia Silk Charge&amp;Go IX si adatta comodamente all&#039;interno dell&#039;orecchio e sfrutta la piattaforma Integrated Xperience per aiutarti a seguire le conversazioni anche negli ambienti pi\u00f9 vivaci. La ricarica quotidiana elimina la necessit\u00e0 di sostituire le batterie, offrendo comfort e semplicit\u00e0 d&#039;uso.<\/p>\n\n\n                            \n                                                        <div class=\"audire-product-features\">\n                                <span class=\"audire-product-features__label\">Caratteristiche Principali:<\/span>\n                                <div class=\"audire-product-features__grid\">\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Design quasi invisibile<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Tecnologia Integrated Xperience<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Custodia di ricarica compatta<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Gestione intuitiva tramite App Signia<\/span>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            \n                                                        <div class=\"audire-product-suitability\">\n                                <strong>Indicato per:<\/strong> Ipoacusie lievi e moderate per chi cerca la massima discrezione.                            <\/div>\n                                                    <\/div>\n\n                        <!-- Destra: Immagine e Certificato -->\n                        <div class=\"audire-product-item-right\">\n                            <div class=\"audire-product-media-card\">\n                                <div class=\"audire-product-media-card__image-container\">\n                                    <img loading=\"lazy\" decoding=\"async\" width=\"1408\" height=\"768\" src=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg\" class=\"audire-product-media-card__image img-fluid\" alt=\"\" srcset=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg 1408w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-300x164.jpg 300w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-1024x559.jpg 1024w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-768x419.jpg 768w\" sizes=\"auto, (max-width: 1408px) 100vw, 1408px\" \/>                                <\/div>\n                                <div class=\"audire-product-media-card__cert\">\n                                    <h4 class=\"audire-product-media-card__cert-title\">Dispositivo Certificato CE<\/h4>\n                                    <p class=\"audire-product-media-card__cert-text\">Standard medico acustico approvato SSN\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n                            <div class=\"audire-product-panel is-active\"\n                    id=\"p-signia-pure-chargego-ix-793\">\n                    <div class=\"audire-product-item-grid\">\n\n                        <!-- Frecce di navigazione desktop fluttuanti ai lati della scheda -->\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--prev\"\n                            aria-label=\"Prodotto precedente\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"15 18 9 12 15 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--next\"\n                            aria-label=\"Prodotto successivo\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"9 18 15 12 9 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Sinistra: Info Prodotto -->\n                        <div class=\"audire-product-item-left\">\n                                                        <div class=\"audire-product-item__meta\">\n                                <span class=\"audire-product-item__tag\">Tecnologia e Comfort<\/span>\n                                <span class=\"audire-product-item__sep\">|<\/span>\n                                <span class=\"audire-product-item__tech\">Tecnologia\n                                    Avanzata<\/span>\n                            <\/div>\n                            \n                            <h3 class=\"audire-product-item__name\">Signia Pure Charge&amp;Go IX<\/h3>\n                            <p class=\"audire-product-item__description\">L\u2019apparecchio acustico ricaricabile che unisce tecnologia avanzata e comfort quotidiano.\r\nElegante, confortevole e progettato per accompagnarti in ogni momento della giornata.\r\nSignia Pure Charge&amp;Go IX sfrutta la piattaforma Integrated Xperience per offrirti\r\nun\u2019esperienza d\u2019ascolto pi\u00f9 naturale e coinvolgente, aiutandoti a seguire le conversazioni\r\nanche negli ambienti pi\u00f9 dinamici.\r\nLa batteria ricaricabile garantisce praticit\u00e0 e autonomia, mentre la connettivit\u00e0 avanzata e\r\nl\u2019App Signia permettono di personalizzare facilmente la tua esperienza d\u2019ascolto.<\/p>\n\n\n                            \n                                                        <div class=\"audire-product-features\">\n                                <span class=\"audire-product-features__label\">Caratteristiche Principali:<\/span>\n                                <div class=\"audire-product-features__grid\">\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Tecnologia Integrated Xperience<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Design elegante e confortevole<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Ricarica semplice e affidabile<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Connettivit\u00e0 e controllo tramite App Signia<\/span>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            \n                                                        <div class=\"audire-product-suitability\">\n                                <strong>Indicato per:<\/strong> chi desidera un&#039;assistenza flessibile, pratica e sempre vicina, anche da casa.                            <\/div>\n                                                    <\/div>\n\n                        <!-- Destra: Immagine e Certificato -->\n                        <div class=\"audire-product-item-right\">\n                            <div class=\"audire-product-media-card\">\n                                <div class=\"audire-product-media-card__image-container\">\n                                    <img loading=\"lazy\" decoding=\"async\" width=\"1408\" height=\"768\" src=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg\" class=\"audire-product-media-card__image img-fluid\" alt=\"\" srcset=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg 1408w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-300x164.jpg 300w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-1024x559.jpg 1024w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-768x419.jpg 768w\" sizes=\"auto, (max-width: 1408px) 100vw, 1408px\" \/>                                <\/div>\n                                <div class=\"audire-product-media-card__cert\">\n                                    <h4 class=\"audire-product-media-card__cert-title\">Dispositivo Certificato CE<\/h4>\n                                    <p class=\"audire-product-media-card__cert-text\">Standard medico acustico approvato SSN\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n                            <div class=\"audire-product-panel \"\n                    id=\"p-connettivita-intelligente-984\">\n                    <div class=\"audire-product-item-grid\">\n\n                        <!-- Frecce di navigazione desktop fluttuanti ai lati della scheda -->\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--prev\"\n                            aria-label=\"Prodotto precedente\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"15 18 9 12 15 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--next\"\n                            aria-label=\"Prodotto successivo\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"9 18 15 12 9 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Sinistra: Info Prodotto -->\n                        <div class=\"audire-product-item-left\">\n                            \n                            <h3 class=\"audire-product-item__name\">Connettivit\u00e0 Intelligente<\/h3>\n                            <p class=\"audire-product-item__description\">Resta sempre connesso ai dispositivi che utilizzi ogni giorno. Gli apparecchi acustici di ultima generazione permettono di ascoltare telefonate, musica e contenuti audio in modo semplice, con un&#039;esperienza d&#039;ascolto pi\u00f9 chiara e naturale.<\/p>\n\n\n                                                        <div class=\"audire-product-specs\">\n                                                                <div class=\"audire-product-specs__item\">\n                                    <span class=\"audire-product-specs__label\">CONNESSIONE<\/span>\n                                    <strong\n                                        class=\"audire-product-specs__value\">Bluetooth\u00ae universale<\/strong>\n                                <\/div>\n                                \n                                                                <div class=\"audire-product-specs__item\">\n                                    <span class=\"audire-product-specs__label\">COMPATIBILIT\u00c0<\/span>\n                                    <strong\n                                        class=\"audire-product-specs__value\">Smartphone, TV e dispositivi audio<\/strong>\n                                <\/div>\n                                                            <\/div>\n                            \n                                                        <div class=\"audire-product-features\">\n                                <span class=\"audire-product-features__label\">Caratteristiche Principali:<\/span>\n                                <div class=\"audire-product-features__grid\">\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Streaming diretto di chiamate e musica<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Compatibilit\u00e0 con dispositivi iOS e Android<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Controllo tramite App dedicata<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Accessori wireless per TV e ascolto<\/span>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            \n                                                    <\/div>\n\n                        <!-- Destra: Immagine e Certificato -->\n                        <div class=\"audire-product-item-right\">\n                            <div class=\"audire-product-media-card\">\n                                <div class=\"audire-product-media-card__image-container\">\n                                    <img loading=\"lazy\" decoding=\"async\" width=\"1408\" height=\"768\" src=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg\" class=\"audire-product-media-card__image img-fluid\" alt=\"\" srcset=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg 1408w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-300x164.jpg 300w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-1024x559.jpg 1024w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-768x419.jpg 768w\" sizes=\"auto, (max-width: 1408px) 100vw, 1408px\" \/>                                <\/div>\n                                <div class=\"audire-product-media-card__cert\">\n                                    <h4 class=\"audire-product-media-card__cert-title\">Dispositivo Certificato CE<\/h4>\n                                    <p class=\"audire-product-media-card__cert-text\">Standard medico acustico approvato SSN\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n                            <div class=\"audire-product-panel \"\n                    id=\"p-telemedicina-986\">\n                    <div class=\"audire-product-item-grid\">\n\n                        <!-- Frecce di navigazione desktop fluttuanti ai lati della scheda -->\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--prev\"\n                            aria-label=\"Prodotto precedente\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"15 18 9 12 15 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n                        <button type=\"button\" class=\"audire-products__panel-arrow audire-products__panel-arrow--next\"\n                            aria-label=\"Prodotto successivo\">\n                            <svg width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\"\n                                stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\">\n                                <polyline points=\"9 18 15 12 9 6\"><\/polyline>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Sinistra: Info Prodotto -->\n                        <div class=\"audire-product-item-left\">\n                            \n                            <h3 class=\"audire-product-item__name\">Telemedicina<\/h3>\n                            <p class=\"audire-product-item__description\">Ricevi supporto professionale anche a distanza. Quando disponibile, il tuo audioprotesista pu\u00f2 effettuare regolazioni dell&#039;apparecchio e offrirti assistenza senza la necessit\u00e0 di recarti sempre in centro.<\/p>\n\n\n                                                        <div class=\"audire-product-specs\">\n                                                                <div class=\"audire-product-specs__item\">\n                                    <span class=\"audire-product-specs__label\">SERVIZIO<\/span>\n                                    <strong\n                                        class=\"audire-product-specs__value\">Regolazioni da remoto<\/strong>\n                                <\/div>\n                                \n                                                                <div class=\"audire-product-specs__item\">\n                                    <span class=\"audire-product-specs__label\">SUPPORTO<\/span>\n                                    <strong\n                                        class=\"audire-product-specs__value\">Assistenza personalizzata online<\/strong>\n                                <\/div>\n                                                            <\/div>\n                            \n                                                        <div class=\"audire-product-features\">\n                                <span class=\"audire-product-features__label\">Caratteristiche Principali:<\/span>\n                                <div class=\"audire-product-features__grid\">\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Regolazioni a distanza dell&#039;apparecchio<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Supporto rapido con l&#039;audioprotesista<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Meno spostamenti, pi\u00f9 comodit\u00e0<\/span>\n                                        <\/div>\n                                                                            <div class=\"audire-product-features__item\">\n                                            <span class=\"audire-product-features__icon\">\u2714<\/span>\n                                            <span>Continuit\u00e0 dell&#039;assistenza nel tempo<\/span>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                            \n                                                        <div class=\"audire-product-suitability\">\n                                <strong>Indicato per:<\/strong> chi desidera un&#039;assistenza flessibile, pratica e sempre vicina, anche da casa.                            <\/div>\n                                                    <\/div>\n\n                        <!-- Destra: Immagine e Certificato -->\n                        <div class=\"audire-product-item-right\">\n                            <div class=\"audire-product-media-card\">\n                                <div class=\"audire-product-media-card__image-container\">\n                                    <img loading=\"lazy\" decoding=\"async\" width=\"1408\" height=\"768\" src=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg\" class=\"audire-product-media-card__image img-fluid\" alt=\"\" srcset=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable.jpg 1408w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-300x164.jpg 300w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-1024x559.jpg 1024w, https:\/\/staging.crmcosmo.com\/audire\/wp-content\/uploads\/2026\/08\/hearing_rechargeable-768x419.jpg 768w\" sizes=\"auto, (max-width: 1408px) 100vw, 1408px\" \/>                                <\/div>\n                                <div class=\"audire-product-media-card__cert\">\n                                    <h4 class=\"audire-product-media-card__cert-title\">Dispositivo Certificato CE<\/h4>\n                                    <p class=\"audire-product-media-card__cert-text\">Standard medico acustico approvato SSN\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n<script>\n    document.addEventListener('DOMContentLoaded', function () {\n        \/\/ Gestione Tab dei Apparecchi Acustici\n        const productsBlocks = document.querySelectorAll('.audire-products');\n        productsBlocks.forEach(function (block) {\n            const tabButtons = Array.from(block.querySelectorAll('.audire-products__tab-btn'));\n            const panels = Array.from(block.querySelectorAll('.audire-product-panel'));\n\n            function activateIndex(index) {\n                const total = tabButtons.length;\n                if (total === 0) return;\n                const newIndex = (index + total) % total;\n\n                tabButtons.forEach((b, i) => {\n                    if (i === newIndex) b.classList.add('is-active');\n                    else b.classList.remove('is-active');\n                });\n\n                panels.forEach((p, i) => {\n                    if (i === newIndex) p.classList.add('is-active');\n                    else p.classList.remove('is-active');\n                });\n            }\n\n            \/\/ Clic sui Tab\n            tabButtons.forEach(function (btn, index) {\n                btn.addEventListener('click', function () {\n                    activateIndex(index);\n                });\n            });\n\n            \/\/ Trova l'indice correntemente attivo\n            function getActiveIndex() {\n                return tabButtons.findIndex(b => b.classList.contains('is-active'));\n            }\n\n            \/\/ Frecce nel wrapper dei tab\n            const arrowPrev = block.querySelector('.audire-products__nav-arrow--prev');\n            const arrowNext = block.querySelector('.audire-products__nav-arrow--next');\n\n            if (arrowPrev) {\n                arrowPrev.addEventListener('click', function () {\n                    activateIndex(getActiveIndex() - 1);\n                });\n            }\n            if (arrowNext) {\n                arrowNext.addEventListener('click', function () {\n                    activateIndex(getActiveIndex() + 1);\n                });\n            }\n\n            \/\/ Frecce fluttuanti desktop dentro i pannelli dei prodotti\n            block.querySelectorAll('.audire-products__panel-arrow--prev').forEach(function (btn) {\n                btn.addEventListener('click', function () {\n                    activateIndex(getActiveIndex() - 1);\n                });\n            });\n            block.querySelectorAll('.audire-products__panel-arrow--next').forEach(function (btn) {\n                btn.addEventListener('click', function () {\n                    activateIndex(getActiveIndex() + 1);\n                });\n            });\n        });\n    });\n<\/script>\n\n<section class=\"audire-values\">\n    <div class=\"audire-values__inner\">\n        <!-- Header sezione -->\n        <div class=\"audire-values__header\">\n            <span class=\"audire-values__badge\">Centri Acustici di Eccellenza<\/span>\n            <h2 class=\"audire-values__title\">La nostra proposta di valore per il tuo udito<\/h2>\n            <p class=\"audire-values__desc\">Garantiamo l&#039;assistenza ravvicinata di un centro locale, abbinata alla strumentazione delle cliniche diagnostiche private romane.<\/p>\n        <\/div>\n\n        <!-- Griglia valori -->\n        <div class=\"audire-values__grid\">\n                            <div class=\"audire-val-card audire-val-card--orange\">\n\n                    <div class=\"audire-val-card__header\">\n                        <h4 class=\"audire-val-card__title\">Valutiamo<\/h4>\n                        <p class=\"audire-val-card__text\">Analizziamo il tuo udito, le tue abitudini e le situazioni di ascolto pi\u00f9 importanti per te.<\/p>\n                    <\/div>\n                                    <\/div>\n                            <div class=\"audire-val-card audire-val-card--blue\">\n\n                    <div class=\"audire-val-card__header\">\n                        <h4 class=\"audire-val-card__title\">Personalizziamo<\/h4>\n                        <p class=\"audire-val-card__text\">Adattiamo la soluzione acustica alle tue esigenze e al tuo stile di vita.<\/p>\n                    <\/div>\n                                    <\/div>\n                            <div class=\"audire-val-card audire-val-card--blue\">\n\n                    <div class=\"audire-val-card__header\">\n                        <h4 class=\"audire-val-card__title\">Accompagniamo<\/h4>\n                        <p class=\"audire-val-card__text\">Ti seguiamo nel tempo con controlli, regolazioni e assistenza continua, anche per le\r\npratiche burocratiche.<\/p>\n                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"audire-contact\" id=\"prenota\">\n    <div class=\"audire-contact__inner\">\n        <div class=\"audire-contact__grid\">\n            \n            <!-- Colonna Medico\/Specialista -->\n            <div class=\"audire-contact__specialist\">\n                <img decoding=\"async\" src=\"https:\/\/staging.crmcosmo.com\/audire\/wp-content\/themes\/cosmosite\/assets\/images\/clinical_specialist.png\" alt=\"Dott.ssa Valentina\" class=\"audire-contact__specialist-img\">\n                <div class=\"audire-contact__specialist-overlay\">\n                    <span class=\"audire-contact__specialist-tag\">SPECIALISTA ACUSTICO<\/span>\n                    <h4 class=\"audire-contact__specialist-name\">Dott.ssa Valentina<\/h4>\n                    <p class=\"audire-contact__specialist-role\">Responsabile Audiometrica della Sede Centrale Audire Roma.<\/p>\n                <\/div>\n            <\/div>\n\n            <!-- Colonna Modulo Prenotazione -->\n            <div class=\"audire-contact__form-wrapper\">\n                <div class=\"audire-contact__form-header\">\n                    <span class=\"audire-contact__form-tag\">VISITA PREVENTIVA GRATUITA<\/span>\n                    <h3 class=\"audire-contact__form-title\">Prenota ora il controllo gratuito dell&#039;udito<\/h3>\n                    <p class=\"audire-contact__form-desc\">Compila il modulo in 30 secondi. I nostri medici e tecnici ti aspetteranno per un esame gratuito della soglia e del condotto uditivo, senza alcuna spesa.<\/p>\n                <\/div>\n\n                <form class=\"audire-contact-form\" action=\"#\" method=\"POST\">\n                    <div class=\"audire-contact-form__row\">\n                        <div class=\"audire-contact-form__group\">\n                            <label class=\"audire-contact-form__label\">Nome e cognome<\/label>\n                            <input type=\"text\" required name=\"full_name\" placeholder=\"E.g., Mario Rossi\" class=\"audire-contact-form__input\">\n                        <\/div>\n                        <div class=\"audire-contact-form__group\">\n                            <label class=\"audire-contact-form__label\">Recapito Telefonico<\/label>\n                            <input type=\"tel\" required name=\"phone\" placeholder=\"E.g., 345 6789012\" class=\"audire-contact-form__input\">\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"audire-contact-form__row\">\n                        <div class=\"audire-contact-form__group\">\n                            <label class=\"audire-contact-form__label\">Sede Convenzionata<\/label>\n                            <select name=\"location\" class=\"audire-contact-form__select\">\n                                <option value=\"Monteverde\">Sede Gianicolense\/Monteverde<\/option>\n                                <option value=\"Balduina\">Balduina c\/o Artemisia Lab<\/option>\n                                <option value=\"Prati\">Prati c\/o Artemisia Lab<\/option>\n                                <option value=\"Colleferro\">Colleferro c\/o Artemisia Lab<\/option>\n                            <\/select>\n                        <\/div>\n                        <div class=\"audire-contact-form__group\">\n                            <label class=\"audire-contact-form__label\">Data Preferenziale<\/label>\n                            <input type=\"date\" required name=\"pref_date\" class=\"audire-contact-form__input\">\n                        <\/div>\n                    <\/div>\n\n                    <button type=\"submit\" class=\"audire-contact-form__submit\">\n                        Prenota Screening Udito\n                    <\/button>\n                <\/form>\n            <\/div>\n\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"audire-locations\" id=\"audire-locations\">\n    <div class=\"audire-locations__inner\">\n\n        <div class=\"audire-locations__layout\">\n            <!-- Sinistra: Pulsantiera elenco Sedi -->\n            <div class=\"audire-locations__list\">\n\n        <div class=\"audire-locations__header\">\n            <span class=\"audire-locations__badge\">Dove Trovarci<\/span>\n            <h2 class=\"audire-locations__title\">I Centri Specializzati Audire Roma<\/h2>\n            <p class=\"audire-locations__description\">Siamo presenti a Roma sia presso la nostra Sede Centrale con attrezzature diagnostiche di ultima generazione, sia all&#039;interno dei prestigiosi centri diagnostici ed analisi Artemisia Lab in tutta la metropoli.<\/p>\n        <\/div>\n                                    <button type=\"button\" \n                            class=\"audire-location-item-btn is-active\" \n                            data-target=\"loc-panel-0\">\n                        <span class=\"audire-location-item-btn__pin\">\ud83d\udccd<\/span>\n                        <div class=\"audire-location-item-btn__content\">\n                            <h4 class=\"audire-location-item-btn__name\">Filiale Centrale Monteverde<\/h4>\n                            <span class=\"audire-location-item-btn__addr\">Via Francesco Palasciano, 27 <\/span>\n                        <\/div>\n                    <\/button>\n                                    <button type=\"button\" \n                            class=\"audire-location-item-btn \" \n                            data-target=\"loc-panel-1\">\n                        <span class=\"audire-location-item-btn__pin\">\ud83d\udccd<\/span>\n                        <div class=\"audire-location-item-btn__content\">\n                            <h4 class=\"audire-location-item-btn__name\">Audire Balduina c\/o Artemisia Lab<\/h4>\n                            <span class=\"audire-location-item-btn__addr\">Via Ugo de Carolis, 88\/C, 00136 Roma RM<\/span>\n                        <\/div>\n                    <\/button>\n                                    <button type=\"button\" \n                            class=\"audire-location-item-btn \" \n                            data-target=\"loc-panel-2\">\n                        <span class=\"audire-location-item-btn__pin\">\ud83d\udccd<\/span>\n                        <div class=\"audire-location-item-btn__content\">\n                            <h4 class=\"audire-location-item-btn__name\">Audire Colleferro<\/h4>\n                            <span class=\"audire-location-item-btn__addr\">Via Consolare Latina, 12, 00034 Colleferro RM<\/span>\n                        <\/div>\n                    <\/button>\n                                    <button type=\"button\" \n                            class=\"audire-location-item-btn \" \n                            data-target=\"loc-panel-3\">\n                        <span class=\"audire-location-item-btn__pin\">\ud83d\udccd<\/span>\n                        <div class=\"audire-location-item-btn__content\">\n                            <h4 class=\"audire-location-item-btn__name\">Audire Sabaudia<\/h4>\n                            <span class=\"audire-location-item-btn__addr\">Via Claudio Villa 1, 04016 Sabaudia (LT)<\/span>\n                        <\/div>\n                    <\/button>\n                                    <button type=\"button\" \n                            class=\"audire-location-item-btn \" \n                            data-target=\"loc-panel-4\">\n                        <span class=\"audire-location-item-btn__pin\">\ud83d\udccd<\/span>\n                        <div class=\"audire-location-item-btn__content\">\n                            <h4 class=\"audire-location-item-btn__name\">Audire Ostia<\/h4>\n                            <span class=\"audire-location-item-btn__addr\">Via Carlo del Greco, 77, 00122 Lido di Ostia (RM)<\/span>\n                        <\/div>\n                    <\/button>\n                            <\/div>\n\n            <!-- Destra: Dettaglio Filiale con Mappa -->\n            <div class=\"audire-locations__detail-container\">\n                                    <div class=\"audire-location-panel is-active\" id=\"loc-panel-0\">\n                        <div class=\"audire-location-detail-card\">\n                            <span class=\"audire-location-detail-card__badge\">FILIALE SELEZIONATA<\/span>\n                            \n                            <h3 class=\"audire-location-detail-card__title\">Audire Roma &#8211; Filiale Centrale Monteverde<\/h3>\n                            <p class=\"audire-location-detail-card__address\">\ud83d\udccd Via Francesco Palasciano, 27 &#8211; 00151 Roma (Zona Gianicolense)<\/p>\n\n                            <div class=\"audire-location-detail-card__specs\">\n                                <p><strong>Orari:<\/strong> Lun &#8211; Ven: 09:00 &#8211; 13:00, 15:00 &#8211; 19:00 | Sab su appuntamento<\/p>\n                                <p><strong>Telefono per appuntamenti:<\/strong> 06 98872425<\/p>\n                                <p class=\"audire-location-detail-card__partner-text\">\ud83d\udee1\ufe0f Filiale Principale dotata di Cabina Silente<\/p>\n                            <\/div>\n\n                            <!-- Mappa simulata GPS -->\n                            <div class=\"audire-location-detail-card__map-box\">\n                                <span class=\"audire-location-detail-card__map-tag\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2970.8946186724415!2d12.4465732!3d41.8736137!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x132f60026250a0df%3A0xbeaf2cfb4d2efee8!2sAudire%20Monteverde!5e0!3m2!1sit!2sit!4v1779957719440!5m2!1sit!2sit\" width=\"100%\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/span>\n                            <\/div>\n\n                            <div class=\"audire-location-detail-card__actions\">\n                                <a href=\"https:\/\/wa.me\/390698872425?text=Vorrei%20informazioni%20su%20test%20udito%20per%20la%20filiale%20di%20Audire+Roma+-+Filiale+Centrale+Monteverde\" target=\"_blank\" class=\"audire-location-action-btn audire-location-action-btn--primary\">\n                                    Chatta su WhatsApp\n                                <\/a>\n                                <a href=\"#prenota\" class=\"audire-location-action-btn audire-location-action-btn--secondary\">\n                                    Richiedi Appuntamento Qui\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"audire-location-panel \" id=\"loc-panel-1\">\n                        <div class=\"audire-location-detail-card\">\n                            <span class=\"audire-location-detail-card__badge\">FILIALE SELEZIONATA<\/span>\n                            \n                            <h3 class=\"audire-location-detail-card__title\">Audire Balduina c\/o Artemisia Lab<\/h3>\n                            <p class=\"audire-location-detail-card__address\">\ud83d\udccd Via Ugo de Carolis, 88\/C, 00136 Roma RM<\/p>\n\n                            <div class=\"audire-location-detail-card__specs\">\n                                <p><strong>Orari:<\/strong> Marted\u00ec: 09:30 &#8211; 12:30 (Su Prenotazione)<\/p>\n                                <p><strong>Telefono per appuntamenti:<\/strong> 06 9818 9448<\/p>\n                                <p class=\"audire-location-detail-card__partner-text\">\ud83d\udee1\ufe0f In convenzione esclusiva con Artemisia Lab Balduina<\/p>\n                            <\/div>\n\n                            <!-- Mappa simulata GPS -->\n                            <div class=\"audire-location-detail-card__map-box\">\n                                <span class=\"audire-location-detail-card__map-tag\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2968.872831886655!2d12.439083199999999!3d41.9170924!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x132f6081f7b813e3%3A0x4ca429ce66106711!2sAudire%20Balduina!5e0!3m2!1sit!2sit!4v1779958096194!5m2!1sit!2sit\" width=\"100%\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/span>\n                            <\/div>\n\n                            <div class=\"audire-location-detail-card__actions\">\n                                <a href=\"https:\/\/wa.me\/390698872425?text=Vorrei%20informazioni%20su%20test%20udito%20per%20la%20filiale%20di%20Audire+Balduina+c%2Fo+Artemisia+Lab\" target=\"_blank\" class=\"audire-location-action-btn audire-location-action-btn--primary\">\n                                    Chatta su WhatsApp\n                                <\/a>\n                                <a href=\"#prenota\" class=\"audire-location-action-btn audire-location-action-btn--secondary\">\n                                    Richiedi Appuntamento Qui\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"audire-location-panel \" id=\"loc-panel-2\">\n                        <div class=\"audire-location-detail-card\">\n                            <span class=\"audire-location-detail-card__badge\">FILIALE SELEZIONATA<\/span>\n                            \n                            <h3 class=\"audire-location-detail-card__title\">Audire Colleferro<\/h3>\n                            <p class=\"audire-location-detail-card__address\">\ud83d\udccd Via Consolare Latina, 12, 00034 Colleferro RM<\/p>\n\n                            <div class=\"audire-location-detail-card__specs\">\n                                <p><strong>Orari:<\/strong> Gioved\u00ec: 15:00 &#8211; 18:30 (Su Prenotazione)<\/p>\n                                <p><strong>Telefono per appuntamenti:<\/strong> 06 8983 5412<\/p>\n                                <p class=\"audire-location-detail-card__partner-text\">\ud83d\udee1\ufe0f In convenzione esclusiva con Artemisia Lab Giulio Cesare<\/p>\n                            <\/div>\n\n                            <!-- Mappa simulata GPS -->\n                            <div class=\"audire-location-detail-card__map-box\">\n                                <span class=\"audire-location-detail-card__map-tag\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2977.708445131105!2d13.005630399999998!3d41.7268098!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1325653d9d7f86c9%3A0xeb479f9dda350542!2sAudire%20Colleferro!5e0!3m2!1sit!2sit!4v1779958310910!5m2!1sit!2sit\" width=\"100%\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/span>\n                            <\/div>\n\n                            <div class=\"audire-location-detail-card__actions\">\n                                <a href=\"https:\/\/wa.me\/390698872425?text=Vorrei%20informazioni%20su%20test%20udito%20per%20la%20filiale%20di%20Audire+Colleferro\" target=\"_blank\" class=\"audire-location-action-btn audire-location-action-btn--primary\">\n                                    Chatta su WhatsApp\n                                <\/a>\n                                <a href=\"#prenota\" class=\"audire-location-action-btn audire-location-action-btn--secondary\">\n                                    Richiedi Appuntamento Qui\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"audire-location-panel \" id=\"loc-panel-3\">\n                        <div class=\"audire-location-detail-card\">\n                            <span class=\"audire-location-detail-card__badge\">FILIALE SELEZIONATA<\/span>\n                            \n                            <h3 class=\"audire-location-detail-card__title\">Audire Sabaudia<\/h3>\n                            <p class=\"audire-location-detail-card__address\">\ud83d\udccd Via Claudio Villa 1, 04016 Sabaudia (LT)<\/p>\n\n                            <div class=\"audire-location-detail-card__specs\">\n                                <p><strong>Orari:<\/strong> Gioved\u00ec: 15:00 &#8211; 18:30 (Su Prenotazione)<\/p>\n                                <p><strong>Telefono per appuntamenti:<\/strong> 07 7328 5541<\/p>\n                                <p class=\"audire-location-detail-card__partner-text\">\ud83d\udee1\ufe0f In convenzione esclusiva con Artemisia Lab Giulio Cesare<\/p>\n                            <\/div>\n\n                            <!-- Mappa simulata GPS -->\n                            <div class=\"audire-location-detail-card__map-box\">\n                                <span class=\"audire-location-detail-card__map-tag\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2997.4155886457506!2d13.041294700000002!3d41.299821900000005!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x13251a5400e34fe1%3A0x393a4ebbf6fd3c79!2sVia%20Claudio%20Villa%2C%201%2C%2004016%20Sabaudia%20LT!5e0!3m2!1sit!2sit!4v1779958527119!5m2!1sit!2sit\" width=\"100%\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/span>\n                            <\/div>\n\n                            <div class=\"audire-location-detail-card__actions\">\n                                <a href=\"https:\/\/wa.me\/390698872425?text=Vorrei%20informazioni%20su%20test%20udito%20per%20la%20filiale%20di%20Audire+Sabaudia\" target=\"_blank\" class=\"audire-location-action-btn audire-location-action-btn--primary\">\n                                    Chatta su WhatsApp\n                                <\/a>\n                                <a href=\"#prenota\" class=\"audire-location-action-btn audire-location-action-btn--secondary\">\n                                    Richiedi Appuntamento Qui\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"audire-location-panel \" id=\"loc-panel-4\">\n                        <div class=\"audire-location-detail-card\">\n                            <span class=\"audire-location-detail-card__badge\">FILIALE SELEZIONATA<\/span>\n                            \n                            <h3 class=\"audire-location-detail-card__title\">Audire Ostia<\/h3>\n                            <p class=\"audire-location-detail-card__address\">\ud83d\udccd Via Carlo del Greco, 77, 00122 Lido di Ostia (RM)<\/p>\n\n                            <div class=\"audire-location-detail-card__specs\">\n                                <p><strong>Orari:<\/strong> Lun &#8211; Ven: 09:00 &#8211; 13:00, 15:00 &#8211; 19:00 | Sab su appuntamento<\/p>\n                                <p><strong>Telefono per appuntamenti:<\/strong> 06 8941 8959<\/p>\n                                <p class=\"audire-location-detail-card__partner-text\">\ud83d\udee1\ufe0f In convenzione esclusiva con Artemisia Lab Ostia Lido<\/p>\n                            <\/div>\n\n                            <!-- Mappa simulata GPS -->\n                            <div class=\"audire-location-detail-card__map-box\">\n                                <span class=\"audire-location-detail-card__map-tag\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2977.364037623378!2d12.288115276478928!3d41.73424017125787!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1325f1b9e4ab5d4f%3A0x53e2e50d33aa544a!2sAudire%20Ostia!5e0!3m2!1sit!2sit!4v1784724696210!5m2!1sit!2sit\" width=\"100%\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/span>\n                            <\/div>\n\n                            <div class=\"audire-location-detail-card__actions\">\n                                <a href=\"https:\/\/wa.me\/390698872425?text=Vorrei%20informazioni%20su%20test%20udito%20per%20la%20filiale%20di%20Audire+Ostia\" target=\"_blank\" class=\"audire-location-action-btn audire-location-action-btn--primary\">\n                                    Chatta su WhatsApp\n                                <\/a>\n                                <a href=\"#prenota\" class=\"audire-location-action-btn audire-location-action-btn--secondary\">\n                                    Richiedi Appuntamento Qui\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    const locationsBlocks = document.querySelectorAll('.audire-locations');\n    locationsBlocks.forEach(function(block) {\n        const buttons = block.querySelectorAll('.audire-location-item-btn');\n        const panels = block.querySelectorAll('.audire-location-panel');\n        \n        buttons.forEach(function(btn) {\n            btn.addEventListener('click', function() {\n                const targetId = this.getAttribute('data-target');\n                \n                \/\/ Rimuovi classe active da bottoni e pannelli del blocco\n                buttons.forEach(b => b.classList.remove('is-active'));\n                panels.forEach(p => p.classList.remove('is-active'));\n                \n                \/\/ Aggiungi attiva\n                this.classList.add('is-active');\n                const targetPanel = block.querySelector('#' + targetId);\n                if (targetPanel) {\n                    targetPanel.classList.add('is-active');\n                }\n            });\n        });\n    });\n});\n<\/script>\n\n\n<section class=\"audire-stats\">\n    <!-- Ribbon partnership -->\n    <div class=\"audire-stats__ribbon-inner\">\n        <div class=\"audire-stats__ribbon-head\">\n            <span class=\"audire-stats__ribbon-sub\">In collaborazione d&#039;eccellenza con<\/span>\n            <h3 class=\"audire-stats__ribbon-title\">Rete Sanitaria Artemisia Lab a Roma<\/h3>\n        <\/div>\n        <div class=\"audire-stats__ribbon-desc\">\n            Consulenza specialistica e diagnostica avanzata uniti a servizio protesico in convenzione esclusiva.        <\/div>\n    <\/div>\n\n    <!-- Griglia statistiche -->\n    <div class=\"audire-stats__grid\">\n                    <div class=\"audire-stats__card\">\n                <span class=\"audire-stats__num\">20+ anni<\/span>\n                <span class=\"audire-stats__label\">Di esperienza acustica<\/span>\n            <\/div>\n                    <div class=\"audire-stats__card\">\n                <span class=\"audire-stats__num\">5 Centri<\/span>\n                <span class=\"audire-stats__label\">Convenzionati su Roma<\/span>\n            <\/div>\n                    <div class=\"audire-stats__card\">\n                <span class=\"audire-stats__num\">4000+<\/span>\n                <span class=\"audire-stats__label\">Pazienti soddisfatti<\/span>\n            <\/div>\n                    <div class=\"audire-stats__card\">\n                <span class=\"audire-stats__num\">100% Gratis<\/span>\n                <span class=\"audire-stats__label\">Controllo acustico preliminare<\/span>\n            <\/div>\n            <\/div>\n<\/section>\n\n\n<section class=\"audire-testimonials\">\n    <div class=\"audire-testimonials__inner\">\n        <div class=\"audire-testimonials__header\">\n            <span class=\"audire-testimonials__badge\">Le recensioni reali dei pazienti<\/span>\n            <h2 class=\"audire-testimonials__title\">Centinaia di romani sono tornati a sentire<\/h2>\n        <\/div>\n\n        <div class=\"audire-testimonials__grid\">\n                            <div class=\"audire-testimonial-card\">\n                    <div class=\"audire-testimonial-card__main\">\n                        <div class=\"audire-testimonial-card__rating\">\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                    <\/div>\n                        <blockquote class=\"audire-testimonial-card__quote\">\n                            &#8220;Dopo anni passati a far finta di capire durante i pranzi di famiglia, ho fatto il controllo dell&#039;udito gratuito da Audire Roma. L&#039;apparecchio ricaricabile invisibile \u00e8 pazzesco, comodo ed \u00e8 sparito ogni timore.&#8221;\n                        <\/blockquote>\n                    <\/div>\n                    <div class=\"audire-testimonial-card__footer\">\n                        <div>\n                            <h4 class=\"audire-testimonial-card__author\">Giovanni Bellini<\/h4>\n                            <span class=\"audire-testimonial-card__meta\">71 anni \u2014\n                                Roma (Monteverde)<\/span>\n                        <\/div>\n                                                    <span class=\"audire-testimonial-card__outcome\">Risolta l&#039;ipoacusia lieve<\/span>\n                                            <\/div>\n                <\/div>\n                            <div class=\"audire-testimonial-card\">\n                    <div class=\"audire-testimonial-card__main\">\n                        <div class=\"audire-testimonial-card__rating\">\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                    <\/div>\n                        <blockquote class=\"audire-testimonial-card__quote\">\n                            &#8220;La cortesia e la precisione del dottore sono state encomiabili. Mi ha spiegato nei dettagli tutte le tecnologie e mi ha fatto testare l&#039;apparecchio per 30 giorni senza alcun impegno.&#8221;\n                        <\/blockquote>\n                    <\/div>\n                    <div class=\"audire-testimonial-card__footer\">\n                        <div>\n                            <h4 class=\"audire-testimonial-card__author\">Maria Rosaria S.<\/h4>\n                            <span class=\"audire-testimonial-card__meta\">65 anni \u2014\n                                Roma (Prati)<\/span>\n                        <\/div>\n                                                    <span class=\"audire-testimonial-card__outcome\">Riacquisita indipendenza d&#039;ascolto<\/span>\n                                            <\/div>\n                <\/div>\n                            <div class=\"audire-testimonial-card\">\n                    <div class=\"audire-testimonial-card__main\">\n                        <div class=\"audire-testimonial-card__rating\">\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                            \u2605\n                                                    <\/div>\n                        <blockquote class=\"audire-testimonial-card__quote\">\n                            &#8220;Soffrivo di ronzio continuo (acufene). Il centro Audire c\/o Artemisia mi ha proposto una terapia sonora che ha cambiato la mia quotidianit\u00e0. Consiglio caldamente la loro competenza professionale.&#8221;\n                        <\/blockquote>\n                    <\/div>\n                    <div class=\"audire-testimonial-card__footer\">\n                        <div>\n                            <h4 class=\"audire-testimonial-card__author\">Ezio M.<\/h4>\n                            <span class=\"audire-testimonial-card__meta\">78 anni \u2014\n                                Colleferro<\/span>\n                        <\/div>\n                                                    <span class=\"audire-testimonial-card__outcome\">Notevole sollievo da acufene severo<\/span>\n                                            <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Homepage - Cosmo Audiology Page<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage - Cosmo Audiology Page\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.crmcosmo.com\/audire\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmo Audiology Page\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-24T08:24:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.crmcosmo.com\/audire\/\",\"url\":\"https:\/\/staging.crmcosmo.com\/audire\/\",\"name\":\"Homepage - Cosmo Audiology Page\",\"isPartOf\":{\"@id\":\"https:\/\/staging.crmcosmo.com\/audire\/#website\"},\"datePublished\":\"2023-01-30T10:29:40+00:00\",\"dateModified\":\"2026-08-24T08:24:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.crmcosmo.com\/audire\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.crmcosmo.com\/audire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.crmcosmo.com\/audire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/staging.crmcosmo.com\/audire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.crmcosmo.com\/audire\/#website\",\"url\":\"https:\/\/staging.crmcosmo.com\/audire\/\",\"name\":\"Cosmo Audiology Page\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.crmcosmo.com\/audire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homepage - Cosmo Audiology Page","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Homepage - Cosmo Audiology Page","og_url":"https:\/\/staging.crmcosmo.com\/audire\/","og_site_name":"Cosmo Audiology Page","article_modified_time":"2026-08-24T08:24:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.crmcosmo.com\/audire\/","url":"https:\/\/staging.crmcosmo.com\/audire\/","name":"Homepage - Cosmo Audiology Page","isPartOf":{"@id":"https:\/\/staging.crmcosmo.com\/audire\/#website"},"datePublished":"2023-01-30T10:29:40+00:00","dateModified":"2026-08-24T08:24:13+00:00","breadcrumb":{"@id":"https:\/\/staging.crmcosmo.com\/audire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.crmcosmo.com\/audire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.crmcosmo.com\/audire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.crmcosmo.com\/audire\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/staging.crmcosmo.com\/audire\/#website","url":"https:\/\/staging.crmcosmo.com\/audire\/","name":"Cosmo Audiology Page","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.crmcosmo.com\/audire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":116,"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":1164,"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/pages\/6\/revisions\/1164"}],"wp:attachment":[{"href":"https:\/\/staging.crmcosmo.com\/audire\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}